{"id":12813,"date":"2022-05-20T11:34:08","date_gmt":"2022-05-20T09:34:08","guid":{"rendered":"https:\/\/www.liveconsent.com\/caracteristici\/zones-speciales\/"},"modified":"2023-05-09T23:02:24","modified_gmt":"2023-05-09T21:02:24","slug":"campuri-speciale","status":"publish","type":"page","link":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/","title":{"rendered":"Campuri speciale"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#8a9fbb 0%|#f2f7ff 100%&#8221; background_color_gradient_start=&#8221;#8a9fbb&#8221; background_color_gradient_end=&#8221;#f2f7ff&#8221; custom_padding=&#8221;0px||||false|false&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_color=&#8221;#faf9ff&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_height_tablet=&#8221;75px&#8221; bottom_divider_height_phone=&#8221;50px&#8221; bottom_divider_height_last_edited=&#8221;on|phone&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.19.5&#8243; _module_preset=&#8221;default&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;75px||100px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Open Sans||||||||&#8221; text_text_color=&#8221;#25436d&#8221; text_font_size=&#8221;17px&#8221; header_font=&#8221;Open Sans|300|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#F2F7FF&#8221; header_font_size=&#8221;52px&#8221; header_line_height=&#8221;1.2em&#8221; header_2_font=&#8221;|300|||||||&#8221; header_2_text_color=&#8221;#25436D&#8221; header_2_font_size=&#8221;30px&#8221; header_2_line_height=&#8221;2em&#8221; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; header_text_align_tablet=&#8221;left&#8221; header_text_align_phone=&#8221;&#8221; header_text_align_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;38px&#8221; header_font_size_phone=&#8221;32px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;24px&#8221; header_2_font_size_phone=&#8221;20px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;1.5em&#8221; header_2_line_height_phone=&#8221;&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;&#8221; text_orientation_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Introduce\u021bi c\u00e2mpuri de formular<br \/>\nla documentele PDF<br \/>\n<\/h1>\n<h2>Zone de text \u0219i casete de selectare pentru a facilita procesul de semnare<\/h2>\n<p>&nbsp;[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#faf9ff&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#3F608E&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Casete de selectare<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1300px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Da\u021bi posibilitatea semnatarilor de a alege cu ajutorul casetelor de selectare&#8221; image=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/checkboxes.png&#8221; alt=&#8221;Consentement simple et rapide&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;67px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Work Sans|600|||||||&#8221; header_text_color=&#8221;#7c9048&#8243; header_font_size=&#8221;25px&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#25436d&#8221; body_font_size=&#8221;15px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; image_max_width=&#8221;67px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]Semnatarii dvs. \u00ee\u0219i pot exprima alegerile \u0219i consim\u021b\u0103m\u00e2ntul cu ajutorul casetelor de selectare pe care le-a\u021bi plasat \u00een documentele trimise pentru semnare.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Introduce\u021bi op\u021biuni \u00een documentele dvs&#8221; image=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/control-system.png&#8221; alt=&#8221;Consentement simple et rapide&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;67px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Work Sans|600|||||||&#8221; header_text_color=&#8221;#7c9048&#8243; header_font_size=&#8221;25px&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#25436d&#8221; body_font_size=&#8221;15px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;left&#8221; hover_enabled=&#8221;0&#8243; image_max_width=&#8221;67px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]Casetele de selectare permit integrarea de op\u021biuni ce trebuie acceptate sau respinse direct \u00een documentele semnate.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_2_text_color=&#8221;#3F608E&#8221; max_width=&#8221;1300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>C\u00e2mpuri de text<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1300px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Introduce\u021bi zone de text pentru completarea de c\u0103tre semnatari.&#8221; image=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/zone-de-texte.png&#8221; alt=&#8221;Consentement simple et rapide&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;67px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Work Sans|600|||||||&#8221; header_text_color=&#8221;#7c9048&#8243; header_font_size=&#8221;25px&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#25436d&#8221; body_font_size=&#8221;15px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; image_max_width=&#8221;67px&#8221; global_colors_info=&#8221;{}&#8221; title__hover_enabled=&#8221;off|desktop&#8221;]Pute\u021bi ad\u0103uga zone pentru introducerea de text, pe care semnatarii dvs. le pot completa \u00eenainte de a semna documentul.[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Transforma\u021bi documentele dvs. de semnat \u00een adev\u0103rate formulare&#8221; image=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/form-view.png&#8221; alt=&#8221;Consentement simple et rapide&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;67px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Work Sans|600|||||||&#8221; header_text_color=&#8221;#7c9048&#8243; header_font_size=&#8221;25px&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#25436d&#8221; body_font_size=&#8221;15px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; hover_enabled=&#8221;0&#8243; image_max_width=&#8221;67px&#8221; global_colors_info=&#8221;{}&#8221; title__hover_enabled=&#8221;off|desktop&#8221; sticky_enabled=&#8221;0&#8243;]Semnatarii pot completa \u0219i \u00eembun\u0103t\u0103\u021bi documentele dvs. \u00een zonele de introducere a textului destinate acestui scop.[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/app.liveconsent.com\/sinscrire\/ESSAI15LC1&#038;source=www&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Descoperi\u021bi gratuit timp de 15 zile&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Bouton pas flottant &#8211; Essayer grat. pdt 15j&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#7c9048&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;5px&#8221; button_font=&#8221;Work Sans||||||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;50px||||false|false&#8221; hover_enabled=&#8221;0&#8243; box_shadow_style=&#8221;preset2&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#b9c890&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#000000&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436D&#8221; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]Pentru a activa op\u021biunea &#8222;c\u00e2mpuri de formular&#8221; \u00een cadrul testului gratuit de 15 zile, v\u0103 rug\u0103m s\u0103 ne contacta\u021bi prin e-mail.[\/et_pb_text][et_pb_button button_url=&#8221;\/ro\/caracteristici\/#caracteristici&#8221; button_text=&#8221;\u00cenapoi la list\u0103&#8221; button_alignment=&#8221;right&#8221; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;Bouton flottant &#8211; Autres fonctionnalit\u00e9s&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#3F608E&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;5px&#8221; button_font=&#8221;Work Sans||||||||&#8221; button_use_icon=&#8221;off&#8221; positioning=&#8221;fixed&#8221; position_origin_a=&#8221;bottom_right&#8221; position_origin_f=&#8221;bottom_right&#8221; position_origin_r=&#8221;bottom_right&#8221; vertical_offset=&#8221;205px&#8221; horizontal_offset=&#8221;-7px&#8221; z_index=&#8221;2&#8243; display_conditions=&#8221;W3siaWQiOiJjYjFjYWM2OC00ZjNiLTRiOTAtOGJiMi1jYzQzZjNhMWZhOWMiLCJjb25kaXRpb24iOiJwYWdlIiwiY29uZGl0aW9uU2V0dGluZ3MiOnsiZHluYW1pY1Bvc3RzRGlzcGxheSI6ImlzTm90IiwiZHluYW1pY1Bvc3RzIjpbeyJsYWJlbCI6IkJQVkYiLCJ2YWx1ZSI6IjgyMzgifV0sInBvc3RUeXBlTGFiZWwiOiJQYWdlcyIsImFkbWluTGFiZWwiOiJQYWdlcyIsImVuYWJsZUNvbmRpdGlvbiI6Im9uIn0sIm9wZXJhdG9yIjoiT1IifV0=&#8221; custom_margin=&#8221;||0px||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; animation_delay=&#8221;5000ms&#8221; hover_enabled=&#8221;0&#8243; box_shadow_style=&#8221;preset2&#8243; box_shadow_horizontal=&#8221;2px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#b9c890&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#000000&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Features&#8221; _builder_version=&#8221;4.17.3&#8243; background_color=&#8221;#faf9ff&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 0%|#faf9ff 99%&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; top_divider_color=&#8221;rgba(255,255,255,0)&#8221; top_divider_height=&#8221;2.5vw&#8221; top_divider_arrangement=&#8221;above_content&#8221; bottom_divider_flip=&#8221;horizontal&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436d&#8221; text_font_size=&#8221;16px&#8221; header_2_font=&#8221;Work Sans|300|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#3F608E&#8221; header_2_font_size=&#8221;45px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;#3f608e&#8221; header_4_font=&#8221;Work Sans|300|||||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;#3F608E&#8221; header_4_font_size=&#8221;30px&#8221; text_orientation=&#8221;center&#8221; animation_direction=&#8221;right&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;30px&#8221; header_4_font_size_phone=&#8221;28px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;justified&#8221; text_orientation_phone=&#8221;justified&#8221; text_orientation_last_edited=&#8221;off|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Cu ajutorul casetelor de selectare<\/h2>\n<h4>LiveConsent faciliteaz\u0103 procesul de semnare<\/h4>\n<p>LiveConsent ofer\u0103 utilizatorilor s\u0103i posibilitatea de a ad\u0103uga zone de formular, printre care se num\u0103r\u0103 casete de selectare \u0219i zone de text.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; padding_top_bottom_link_1=&#8221;true&#8221; padding_top_bottom_link_2=&#8221;true&#8221; padding_top_bottom_link_3=&#8221;true&#8221; padding_left_right_link_1=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; padding_left_right_link_3=&#8221;true&#8221; module_id=&#8221;caseta-de-selectare&#8221; module_class=&#8221; et_pb_row_fullwidth&#8221; _builder_version=&#8221;4.21.0&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0|0px|0px|0px|false|false&#8221; hover_enabled=&#8221;0&#8243; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; custom_padding=&#8221;80px|4%||4%|false|false&#8221; custom_padding_tablet=&#8221;|10%||10%||true&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|10%||10%||true&#8221; padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221; padding_phone=&#8221;|10%||10%||true&#8221;][et_pb_video src=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/case-a-cocher.mp4&#8243; play_icon_color=&#8221;#7C9048&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436d&#8221; text_font_size=&#8221;16px&#8221; link_text_color=&#8221;#7C9048&#8243; header_2_font=&#8221;Work Sans||||||||&#8221; header_2_text_color=&#8221;#25436d&#8221; header_2_font_size=&#8221;40px&#8221; header_4_font=&#8221;Work Sans|300|||||||&#8221; header_4_text_color=&#8221;#25436d&#8221; header_4_font_size=&#8221;25px&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; custom_margin_tablet=&#8221;50px||150px||false|false&#8221; custom_margin_phone=&#8221;50px||150px||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||15px|false|false&#8221; animation_direction=&#8221;right&#8221; hover_enabled=&#8221;0&#8243; border_width_left=&#8221;3px&#8221; border_color_left=&#8221;#7c9048&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]Cu ajutorul casetelor de selectare, semnatarii pot exprima direct op\u021biunile \u0219i consim\u021b\u0103m\u00e2ntul \u00een contractul semnat. [\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; custom_padding=&#8221;80px|4%||4%|false|false&#8221; custom_padding_tablet=&#8221;|10%||10%||true&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|10%||10%||true&#8221; padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221; padding_phone=&#8221;|10%||10%||true&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436d&#8221; text_font_size=&#8221;16px&#8221; header_2_font=&#8221;Work Sans|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F608E&#8221; header_2_font_size=&#8221;45px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;#3f608e&#8221; header_4_font=&#8221;Work Sans|300|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#3F608E&#8221; header_4_font_size=&#8221;30px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;|15%|50px|-5%|false|false&#8221; custom_margin_tablet=&#8221;-150px|0%||0%|false|true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_direction=&#8221;right&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;30px&#8221; header_4_font_size_phone=&#8221;28px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;justified&#8221; text_orientation_phone=&#8221;justified&#8221; text_orientation_last_edited=&#8221;off|phone&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>Casete de selectare<\/h2>\n<h4>Ce este o caset\u0103 de selectare?<\/h4>\n<p>Caseta de selectare este un element de formular care permite utilizatorului s\u0103 \u00ee\u0219i indice op\u021biunile. Utilizatorul poate bifa\/dezbifa o caset\u0103 pur \u0219i simplu f\u0103c\u00e2nd clic pe ea. Aceast\u0103 func\u021bie poate fi util\u0103 \u00een timpul unei v\u00e2nz\u0103ri sau pentru a da consim\u021b\u0103m\u00e2ntul, de exemplu, prin acceptarea termenilor \u0219i condi\u021biilor de v\u00e2nzare.<\/p>\n<p>Este important de \u0219tiut c\u0103 se poate face ca validarea casetelor de selectare s\u0103 fie obligatorie \u00eenainte de aplicarea semn\u0103turii.<\/p>\n<p>&nbsp;<\/p>\n<h4>Cum se utilizeaz\u0103 caseta de selectare?<\/h4>\n<p>C\u00e2nd ajunge\u021bi la <strong>pasul 3<\/strong> de creare a unei aplica\u021bii :<\/p>\n<ol>\n<li>Merge\u021bi la fila &#8222;C\u00e2mpuri formular&#8221;<\/li>\n<li>Alege\u021bi semnatarul dvs<\/li>\n<li>Face\u021bi clic pe pictograma <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2023\/05\/check-box-lc.png\" alt=\"\" class=\"wp-image-12835 alignnone size-full\" width=\"30\" height=\"30\" \/> &#8222;Caseta de selectare&#8221;<\/li>\n<li>A\u0219eza\u021bi casetele acolo unde dori\u021bi<\/li>\n<li>Repeta\u021bi de c\u00e2te ori este necesar<\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; padding_top_bottom_link_1=&#8221;true&#8221; padding_top_bottom_link_2=&#8221;true&#8221; padding_top_bottom_link_3=&#8221;true&#8221; padding_left_right_link_1=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; padding_left_right_link_3=&#8221;true&#8221; module_id=&#8221;camp-de-text&#8221; module_class=&#8221; et_pb_row_fullwidth inverse&#8221; _builder_version=&#8221;4.21.0&#8243; width=&#8221;100%&#8221; width_tablet=&#8221;100%&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|desktop&#8221; max_width=&#8221;100%&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|desktop&#8221; custom_padding=&#8221;0|0px|0px|0px|false|false&#8221; hover_enabled=&#8221;0&#8243; make_fullwidth=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; custom_padding=&#8221;80px|4%||4%|false|false&#8221; custom_padding_tablet=&#8221;|10%||10%||true&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|10%||10%||true&#8221; padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221; padding_phone=&#8221;|10%||10%||true&#8221;][et_pb_video src=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/zone-texte.mp4&#8243; play_icon_color=&#8221;#7C9048&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; box_shadow_style=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436d&#8221; text_font_size=&#8221;16px&#8221; link_text_color=&#8221;#7C9048&#8243; header_2_font=&#8221;Work Sans||||||||&#8221; header_2_text_color=&#8221;#25436d&#8221; header_2_font_size=&#8221;40px&#8221; header_4_font=&#8221;Work Sans|300|||||||&#8221; header_4_text_color=&#8221;#25436d&#8221; header_4_font_size=&#8221;25px&#8221; custom_margin=&#8221;50px||50px||true|false&#8221; custom_margin_tablet=&#8221;50px||150px||false|false&#8221; custom_margin_phone=&#8221;50px||150px||false|false&#8221; custom_margin_last_edited=&#8221;on|tablet&#8221; custom_padding=&#8221;|||15px|false|false&#8221; animation_direction=&#8221;right&#8221; hover_enabled=&#8221;0&#8243; border_width_left=&#8221;3px&#8221; border_color_left=&#8221;#7c9048&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]Permite\u021bi semnatarilor s\u0103 completeze informa\u021biile \u00een mod simplu atunci c\u00e2nd semneaz\u0103.[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; background_enable_color=&#8221;off&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; custom_padding=&#8221;80px|4%||4%|false|false&#8221; custom_padding_tablet=&#8221;|10%||10%||true&#8221; custom_padding_phone=&#8221;&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221; padding_tablet=&#8221;|10%||10%||true&#8221; padding_last_edited=&#8221;on|tablet&#8221; custom_padding__hover=&#8221;|||&#8221; padding_phone=&#8221;|10%||10%||true&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436d&#8221; text_font_size=&#8221;16px&#8221; header_2_font=&#8221;Work Sans|300|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#3F608E&#8221; header_2_font_size=&#8221;45px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;#3f608e&#8221; header_4_font=&#8221;Work Sans|300|||||||&#8221; header_4_text_align=&#8221;left&#8221; header_4_text_color=&#8221;#3F608E&#8221; header_4_font_size=&#8221;30px&#8221; text_orientation=&#8221;justified&#8221; custom_margin=&#8221;|15%|50px|-5%|false|false&#8221; custom_margin_tablet=&#8221;-150px|0%||0%|false|true&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; animation_direction=&#8221;right&#8221; hover_enabled=&#8221;0&#8243; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;35px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_4_text_align_tablet=&#8221;left&#8221; header_4_text_align_phone=&#8221;left&#8221; header_4_text_align_last_edited=&#8221;on|phone&#8221; header_4_font_size_tablet=&#8221;30px&#8221; header_4_font_size_phone=&#8221;28px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;justified&#8221; text_orientation_phone=&#8221;justified&#8221; text_orientation_last_edited=&#8221;off|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>C\u00e2mp de text<\/h2>\n<h4>Ce este un c\u00e2mp de text ?<\/h4>\n<p>C\u00e2mpurile de text pot fi utilizate pentru a colecta informa\u021bii suplimentare referitoare la documentul ce trebuie semnat de c\u0103tre semnatar.<\/p>\n<p>Aceste c\u00e2mpuri de text reprezint\u0103 zone de introducere a textului ce permit completarea cu una sau mai multe linii de text. Ele pot fi necesare atunci c\u00e2nd se solicit\u0103 introducerea de informa\u021bii precum numele sau prenumele.<\/p>\n<p>&nbsp;<\/p>\n<h4>Comment utiliser les zones textes ?<\/h4>\n<p>C\u00e2nd ajunge\u021bi la <strong>pasul 3<\/strong> de creare a unei aplica\u021bii :<\/p>\n<ol>\n<li>Merge\u021bi la fila &#8222;C\u00e2mpuri formular&#8221;<\/li>\n<li>Alege\u021bi semnatarul dvs.<\/li>\n<li>Face\u021bi clic pe pictograma <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2023\/05\/add-text-lc.png\" alt=\"\" class=\"wp-image-12845 alignnone size-full\" width=\"39\" height=\"30\" \/> \u201cC\u00e2mp de text\u201c<\/li>\n<li>A\u0219eza\u021bi zonele \u00een loca\u021biile dorite<\/li>\n<li>Repeta\u021bi opera\u021biunea de c\u00e2te ori este necesar<\/li>\n<\/ol>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#3F608E&#8221; max_width=&#8221;1300px&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h2>De asemenea, pute\u021bi descoperi \u0219i op\u021biunea de parafe<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.17.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;1300px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Parafarea documentelor PDF&#8221; url=&#8221;\/ro\/caracteristici\/initiale-pdf\/&#8221; image=&#8221;https:\/\/www.liveconsent.com\/wp-content\/uploads\/2021\/10\/files-paraphe3.png&#8221; alt=&#8221;Consentement simple et rapide&#8221; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;67px&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Work Sans|600|||||||&#8221; header_text_color=&#8221;#7c9048&#8243; header_font_size=&#8221;25px&#8221; body_font=&#8221;Open Sans||||||||&#8221; body_text_color=&#8221;#25436d&#8221; body_font_size=&#8221;15px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;right&#8221; link_option_url=&#8221;\/fonctionnalites\/parapher-pdf\/&#8221; hover_enabled=&#8221;0&#8243; image_max_width=&#8221;67px&#8221; global_colors_info=&#8221;{}&#8221; title__hover_enabled=&#8221;off|desktop&#8221; sticky_enabled=&#8221;0&#8243;]Simplifica\u021bi semn\u0103tura cu paraf\u0103 pentru fi\u0219ierele PDF prin oferirea unei experien\u021be de utilizare u\u0219oar\u0103.[\/et_pb_blurb][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_text_color=&#8221;#25436D&#8221; text_orientation=&#8221;center&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]Contacta\u021bi-ne prin e-mail pentru a ob\u021bine activarea op\u021biunii de paraf\u0103 \u00een cadrul perioadei de test gratuit de 15 zile.[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#faf9ff&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(222,230,200,0.45) 0%|#faf9ff 100%&#8221; background_color_gradient_start=&#8221;rgba(222,230,200,0.45)&#8221; background_color_gradient_end=&#8221;#faf9ff&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;100px||100px||true|false&#8221; top_divider_style=&#8221;waves2&#8243; top_divider_height=&#8221;80px&#8221; top_divider_height_tablet=&#8221;75px&#8221; top_divider_height_phone=&#8221;50px&#8221; top_divider_height_last_edited=&#8221;on|desktop&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||||false|false&#8221; custom_css_main_element=&#8221;display: flex !important;||align-items: center !important;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Work Sans|300|||||||&#8221; text_text_color=&#8221;#3F608E&#8221; text_font_size=&#8221;24px&#8221; text_line_height=&#8221;1.2em&#8221; header_4_text_color=&#8221;#25436D&#8221; header_4_font_size=&#8221;24px&#8221; hover_enabled=&#8221;0&#8243; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;left&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Platforma noastr\u0103 este una dintre pu\u021binele solu\u021bii de semn\u0103tur\u0103 electronic\u0103 care ofer\u0103 un serviciu simplu pentru a ad\u0103uga c\u00e2mpuri de formular la un document online.<\/p>\n<p>Pute\u021bi ad\u0103uga \u00een documente c\u00e2mpuri de text sau casete de selectare care pot fi completate de semnatarii dumneavoastr\u0103. Aceast\u0103 op\u021biune de &#8222;C\u00e2mpuri de formulare&#8221; este disponibil\u0103 \u00een plus fa\u021b\u0103 de abonamente \u0219i poate fi achizi\u021bionat\u0103 prin intermediul consultantului dumneavoastr\u0103 LiveConsent.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/app.liveconsent.com\/sinscrire\/ESSAI15LC1&#038;source=www&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Descoperi\u021bi gratuit timp de 15 zile&#8221; button_alignment=&#8221;center&#8221; admin_label=&#8221;Bouton pas flottant &#8211; Essayer grat. pdt 15j&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#7c9048&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;5px&#8221; button_font=&#8221;Work Sans||||||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;50px||||false|false&#8221; hover_enabled=&#8221;0&#8243; box_shadow_style=&#8221;preset2&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#b9c890&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#000000&#8243; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#faf9ff&#8221; z_index=&#8221;1&#8243; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_color=&#8221;#3f608e&#8221; bottom_divider_height=&#8221;60px&#8221; bottom_divider_height_tablet=&#8221;40px&#8221; bottom_divider_height_phone=&#8221;30px&#8221; bottom_divider_height_last_edited=&#8221;on|phone&#8221; da_disable_devices=&#8221;off|off|off&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Introduce\u021bi c\u00e2mpuri de formular la documentele PDF Zone de text \u0219i casete de selectare pentru a facilita procesul de semnare &nbsp;Casete de selectareSemnatarii dvs. \u00ee\u0219i pot exprima alegerile \u0219i consim\u021b\u0103m\u00e2ntul cu ajutorul casetelor de selectare pe care le-a\u021bi plasat \u00een documentele trimise pentru semnare.Casetele de selectare permit integrarea de op\u021biuni ce trebuie acceptate sau respinse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10500,"parent":12634,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-12813","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cases \u00e0 cocher et champs texte | Cr\u00e9ez vos propres formulaires<\/title>\n<meta name=\"description\" content=\"Vous pouvez ajouter des cases \u00e0 cocher et des zones de textes modifiables \u00e0 vos documents avant de les envoyer pour signature.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cases \u00e0 cocher et champs texte | Cr\u00e9ez vos propres formulaires\" \/>\n<meta property=\"og:description\" content=\"Vous pouvez ajouter des cases \u00e0 cocher et des zones de textes modifiables \u00e0 vos documents avant de les envoyer pour signature.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/\" \/>\n<meta property=\"og:site_name\" content=\"LiveConsent\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-09T21:02:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1950\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/\",\"url\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/\",\"name\":\"Cases \u00e0 cocher et champs texte | Cr\u00e9ez vos propres formulaires\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liveconsent.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg\",\"datePublished\":\"2022-05-20T09:34:08+00:00\",\"dateModified\":\"2023-05-09T21:02:24+00:00\",\"description\":\"Vous pouvez ajouter des cases \u00e0 cocher et des zones de textes modifiables \u00e0 vos documents avant de les envoyer pour signature.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.liveconsent.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg\",\"contentUrl\":\"https:\\\/\\\/www.liveconsent.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg\",\"width\":1950,\"height\":1300,\"caption\":\"Casetele de selectare \u0219i c\u00e2mpurile de text simplific\u0103 semnarea documentelor PDF.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/caracteristici\\\/campuri-speciale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caracteristicile solutiei de semn\u0103tur\u0103 electronic\u0103 avansat\u0103\",\"item\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/fonctionnalites\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Campuri speciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/\",\"name\":\"LiveConsent\",\"description\":\"Signature \u00c9lectronique\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.liveconsent.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cases \u00e0 cocher et champs texte | Cr\u00e9ez vos propres formulaires","description":"Vous pouvez ajouter des cases \u00e0 cocher et des zones de textes modifiables \u00e0 vos documents avant de les envoyer pour signature.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/","og_locale":"ro_RO","og_type":"article","og_title":"Cases \u00e0 cocher et champs texte | Cr\u00e9ez vos propres formulaires","og_description":"Vous pouvez ajouter des cases \u00e0 cocher et des zones de textes modifiables \u00e0 vos documents avant de les envoyer pour signature.","og_url":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/","og_site_name":"LiveConsent","article_modified_time":"2023-05-09T21:02:24+00:00","og_image":[{"width":1950,"height":1300,"url":"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"19 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/","url":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/","name":"Cases \u00e0 cocher et champs texte | Cr\u00e9ez vos propres formulaires","isPartOf":{"@id":"https:\/\/www.liveconsent.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/#primaryimage"},"image":{"@id":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg","datePublished":"2022-05-20T09:34:08+00:00","dateModified":"2023-05-09T21:02:24+00:00","description":"Vous pouvez ajouter des cases \u00e0 cocher et des zones de textes modifiables \u00e0 vos documents avant de les envoyer pour signature.","breadcrumb":{"@id":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/#primaryimage","url":"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg","contentUrl":"https:\/\/www.liveconsent.com\/wp-content\/uploads\/2022\/05\/businesswoman-filling-last-will-and-testament-form-2021-08-28-17-56-04-utc.jpg","width":1950,"height":1300,"caption":"Casetele de selectare \u0219i c\u00e2mpurile de text simplific\u0103 semnarea documentelor PDF."},{"@type":"BreadcrumbList","@id":"https:\/\/www.liveconsent.com\/ro\/caracteristici\/campuri-speciale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.liveconsent.com\/ro\/"},{"@type":"ListItem","position":2,"name":"Caracteristicile solutiei de semn\u0103tur\u0103 electronic\u0103 avansat\u0103","item":"https:\/\/www.liveconsent.com\/ro\/fonctionnalites\/"},{"@type":"ListItem","position":3,"name":"Campuri speciale"}]},{"@type":"WebSite","@id":"https:\/\/www.liveconsent.com\/ro\/#website","url":"https:\/\/www.liveconsent.com\/ro\/","name":"LiveConsent","description":"Signature \u00c9lectronique","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liveconsent.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/pages\/12813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/comments?post=12813"}],"version-history":[{"count":11,"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/pages\/12813\/revisions"}],"predecessor-version":[{"id":12863,"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/pages\/12813\/revisions\/12863"}],"up":[{"embeddable":true,"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/pages\/12634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/media\/10500"}],"wp:attachment":[{"href":"https:\/\/www.liveconsent.com\/ro\/wp-json\/wp\/v2\/media?parent=12813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}